{"id":78657,"date":"2025-02-12T08:54:24","date_gmt":"2025-02-12T07:54:24","guid":{"rendered":"https:\/\/www.robisa.es\/?p=78657"},"modified":"2025-02-12T09:13:49","modified_gmt":"2025-02-12T08:13:49","slug":"nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird","status":"publish","type":"post","link":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/","title":{"rendered":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird"},"content":{"rendered":"<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><h1 style=\"text-align: center;\"><strong>Angelbird revoluciona o armazenamento com os seus novos cart\u00f5es AV PRO SE CFexpress v4 Tipo B<\/strong><\/h1>\n<\/div><\/section><\/div>\n<div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><div class='avia-image-container  av-styling-    avia-align-center '  ><div class='avia-image-container-inner'><img class='avia_image ' src='https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/02_-2.jpg' alt='' title='02_'   \/><\/div><\/div><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><p style=\"text-align: right;\"><strong>Lisboa, 11 de fevereiro de 2025<\/strong><\/p>\n<p>A Angelbird, empresa austr\u00edaca dedicada \u00e0 produ\u00e7\u00e3o de cart\u00f5es de mem\u00f3ria e solu\u00e7\u00f5es de armazenamento distribu\u00edda em Portugal pela Robisa, orgulha-se de apresentar os seus novos cart\u00f5es de mem\u00f3ria AV PRO SE CFexpress v4 Tipo B, concebidos com a tecnologia de armazenamento mais avan\u00e7ada para a produ\u00e7\u00e3o de conte\u00fados. Baseados na \u00faltima gera\u00e7\u00e3o de CFexpress v4 Tipo B, estes cart\u00f5es estabelecem uma nova refer\u00eancia em termos de desempenho est\u00e1vel e de alta velocidade, redefinindo o conceito de <em>Standard Edition<\/em> na gama de cart\u00f5es CFexpress Tipo B.<\/p>\n<h2>\u201cO nosso objetivo \u00e9 claro: desempenho inigual\u00e1vel, compatibilidade absoluta e a mais elevada fiabilidade, concebidos para os desafios atuais e prontos para o futuro.\u201d Roman Rabitsch, fundador e CEO da Angelbird<\/h2>\n<\/div><\/section><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><p><strong>Desempenho r\u00e1pido e est\u00e1vel<\/strong><\/p>\n<p>Os cart\u00f5es AV PRO SE CFexpress v4 Tipo B foram concebidos para oferecer uma solu\u00e7\u00e3o vers\u00e1til para uma variedade de cargas de trabalho de produ\u00e7\u00e3o audiovisual. Gra\u00e7as \u00e0 tecnologia Stable Stream, asseguram um desempenho de grava\u00e7\u00e3o consistente em todos os modos e durante toda a capacidade do cart\u00e3o. Com velocidades de escrita sustentadas de at\u00e9 3150 MB\/s, duplicam a velocidade das vers\u00f5es anteriores CFexpress v2 Tipo B, garantindo uma fluidez impec\u00e1vel em ambientes de grava\u00e7\u00e3o exigentes e p\u00f3s-produ\u00e7\u00e3o com grande volume de dados.<\/p>\n<\/div><\/section><\/div>\n<div class=\"flex_column av_one_half  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><p><div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<div class='avia-image-container  av-styling-    avia-align-center '  ><div class='avia-image-container-inner'><img class='avia_image ' src='https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/Angelbird-AV-PRO-SE-CFexpress-1TB-2TB-4TB-Media-Tank-Card-Reader-PKT-Canon-1030x687.jpg' alt='' title='Angelbird-AV-PRO-SE-CFexpress-1TB-2TB-4TB-Media-Tank-Card-Reader-PKT-Canon'   \/><\/div><\/div><br \/>\n<div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><h3><strong>Principais funcionalidades<\/strong><\/h3>\n<\/div><\/section><br \/>\n<section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><ul>\n<li>Tecnologia CFexpress v4 Tipo B l\u00edder da ind\u00fastria com interface PCIe 4.0 avan\u00e7ada para grava\u00e7\u00e3o a alta velocidade e transfer\u00eancia r\u00e1pida;<\/li>\n<li>Produ\u00e7\u00e3o sem limites: concebidos para a produ\u00e7\u00e3o de v\u00eddeo com grande volume de dados e para a produ\u00e7\u00e3o de fotografias de alta velocidade em RAW, at\u00e9 12K+ e mais;<\/li>\n<li>Desempenho de leitura\/escrita ininterrupto Stable Stream em toda a capacidade do cart\u00e3o;<\/li>\n<li>A prote\u00e7\u00e3o t\u00e9rmica ativa garante um funcionamento seguro em ambientes extremos e evita o sobreaquecimento do cart\u00e3o;<\/li>\n<li>Cart\u00e3o concebido para durar e suportar temperaturas entre -12 \u00b0C e 72 \u00b0C;<\/li>\n<li>Amplamente compat\u00edvel, com atualiza\u00e7\u00f5es de firmware que asseguram a compatibilidade com futuros modelos de c\u00e2maras, novas funcionalidades e codecs (as atualiza\u00e7\u00f5es podem ser efetuadas diretamente nos cart\u00f5es utilizando um leitor de cart\u00f5es Angelbird);<\/li>\n<li>Compat\u00edvel com vers\u00f5es mais antigas de todos os modelos de c\u00e2maras que utilizam o formato de cart\u00e3o de mem\u00f3ria CFexpress Tipo B, incluindo modelos antigos e fora do mercado;<\/li>\n<li>Servi\u00e7o interno de recupera\u00e7\u00e3o de dados a n\u00edvel de hardware e software;<\/li>\n<li>Garantia de 3 anos.<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<div class=\"flex_column av_one_half  flex_column_div av-zero-column-padding   \" style='border-radius:0px; '><p><div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<div class='avia-image-container  av-styling-    avia-align-center '  ><div class='avia-image-container-inner'><a href='https:\/\/www.robisa.es\/shop\/angelbird\/2456-lectores-de-tarjetas-pkt-cfexpress-b-9120056587117.html' class='avia_image'   target=\"_blank\" ><img class='avia_image ' src='https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/Angelbird-AV-PRO-SE-CFexpress-B-1TB-Card-Reader-PKT-2-1030x687.jpg' alt='' title='Angelbird-AV-PRO-SE-CFexpress-B-1TB-Card-Reader-PKT-2'  \/><\/a><\/div><\/div><br \/>\n<div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div><br \/>\n<section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><h3><strong>Especifica\u00e7\u00f5es t\u00e9cnicas<\/strong><\/h3>\n<\/div><\/section><br \/>\n<section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><ul>\n<li>Capacidades dispon\u00edveis: 512 GB, 1 TB, 2 TB e 4 TB;<\/li>\n<li>Dimens\u00f5es: 38,5 \u00d7 3,8 \u00d7 29,8 mm;<\/li>\n<li>Peso: ~7 g;<\/li>\n<li>Interface: CFexpress v4 Tipo B, PCIe 4.0 x2;<\/li>\n<li>Prote\u00e7\u00e3o avan\u00e7ada: sensor de temperatura, TRIM2, ECC, EMS, SMART2 e gest\u00e3o de energia;<\/li>\n<li>Concebidos para um consumo m\u00ednimo de energia, maximizando a dura\u00e7\u00e3o da bateria da c\u00e2mara;<\/li>\n<li>Certifica\u00e7\u00f5es: CE, RoHS, FCC, UKCA, RCM, REACH, KC.<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><p><strong>Garantia de 3 anos e servi\u00e7o de recupera\u00e7\u00e3o de dados interno gratuito<\/strong><\/p>\n<p>A principal vantagem do famoso servi\u00e7o de apoio ao cliente da Angelbird \u00e9 que \u00e9 um servi\u00e7o interno gratuito de recupera\u00e7\u00e3o de dados ao n\u00edvel do hardware e do software para os produtos Angelbird, ativado atrav\u00e9s do website da Angelbird no prazo de 30 dias ap\u00f3s a compra.<\/p>\n<\/div><\/section><\/div>\n<div style=' margin-top:25px; margin-bottom:25px;'  class='hr hr-custom hr-center hr-icon-no  '><span class='hr-inner   inner-border-av-border-fat' style=' width:1800px; border-color:#d6f600;' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><h3 style=\"text-align: left;\"><span style=\"font-family: montserrat;\"><strong>Caracter\u00edsticas t\u00e9cnicas AV PRO CFexpress&#x2122; v4 TipoB<\/strong><\/span><\/h3>\n<\/div><\/section><br \/>\n<section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><h3 style=\"text-align: center;\"><\/h3>\n<table class=\" aligncenter\" style=\"width: 93.154%;\" width=\"623\">\n<tbody>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\"><\/td>\n<td style=\"width: 176.681%;\" width=\"510\"><span style=\"font-family: montserrat;\"><strong>\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Descri\u00e7\u00e3o<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">Suporte de ultra-alta velocidade com tecnologia v4 preparado para o futuro, ideal para produ\u00e7\u00e3o de v\u00eddeo e fotografia 12K+ RAW.<\/p>\n<p>Tipo: CFexpress&#x2122; Tipo B<br \/>\nModelo: MK2<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Capacidades dispon\u00edveis<\/td>\n<td style=\"width: 176.681%;\" width=\"510\"><strong><span style=\"font-family: montserrat;\">512 GB |1 TB 2 TB, 4 TB<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Velocidades m\u00e1ximas de acordo com a capacidade<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">512 GB: M\u00e1x. 3700 MB\/s, grava\u00e7\u00e3o m\u00e1xima 1100MB\/s<\/p>\n<p>1 TB: leitura m\u00e1xima 3700 MB\/s, grava\u00e7\u00e3o m\u00e1xima 2300MB\/s<\/p>\n<p>2 TB &#8211; 4 TB: leitura m\u00e1xima 3700 MB\/s, grava\u00e7\u00e3o m\u00e1xima 3500MB\/s<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Velocidades sustentadas de acordo com a capacidade<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">512GB: Leitura. 3500 MB\/s, Escrita. 1050MB\/s<\/p>\n<p>1TB: Leitura. 3500 MB\/s, Escrita. 2100MB\/s<\/p>\n<p>2 TB &#8211; 4 TB: Ler. 3500 MB\/s, Escrita. 3150MB\/s<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Consumo m\u00ednimo de energia<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">Para manter a bateria da c\u00e2mara ligada o maior tempo poss\u00edvel. Tens\u00e3o de entrada CC: 3,3 V \u00b1 10% Utiliza\u00e7\u00e3o de energia (inativo\/m\u00e1ximo) Suspens\u00e3o &lt; 50 mW Inativo 800 mW M\u00e1x. at\u00e9 3,75W<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Corrente Est\u00e1vel&#x2122;<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">Desempenho consistente de leitura e escrita em toda a capacidade<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Dimens\u00f5es e peso<\/td>\n<td style=\"width: 176.681%;\" width=\"510\"><span style=\"font-family: montserrat;\">38.5 \u00d7 3.8 \u00d7 29.8 mm ~7 g | 0.25 oz<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.2047%;\" width=\"113\">Qualidade de constru\u00e7\u00e3o s\u00f3lida<\/td>\n<td style=\"width: 176.681%;\" width=\"510\">Resist\u00eancia ao choque<br \/>\n(N\u00e3o operacional): 50GResist\u00eancia \u00e0 vibra\u00e7\u00e3o<br \/>\n(N\u00e3o operacional): 15G<\/p>\n<p>Resist\u00eancia \u00e0 temperatura<br \/>\nEm funcionamento:<br \/>\n-12\u00baC | 72\u00b0C<br \/>\n10\u00b0F | 162\u00b0F<\/p>\n<p>Armazenar:<br \/>\n-40\u00baC | 85\u00b0C<br \/>\n-40\u00b0F | 185\u00b0F<\/p>\n<p>Humidade operacional<br \/>\n5% a 95% (sem condensa\u00e7\u00e3o)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/section><\/p><\/div>\n<div style='height:50px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<div class=\"flex_column av_one_third  flex_column_div av-zero-column-padding first  \" style='border-radius:0px; '><div class='avia-image-container  av-styling-    avia-align-left '  ><div class='avia-image-container-inner'><img class='avia_image ' src='https:\/\/www.robisa.es\/wp-content\/uploads\/2022\/02\/Angelbird-1.jpg' alt='' title='Angelbird'   \/><\/div><\/div><\/div>\n<div class=\"flex_column av_two_third  flex_column_div av-zero-column-padding   \" style='border-radius:0px; '><section class=\"av_textblock_section \" ><div class='avia_textblock  '  ><p><strong>Sobre a Angelbird<br \/>\n<\/strong>A Angelbird Technologies \u00e9 uma empresa austr\u00edaca dedicada \u00e0 busca de tecnologia superior, projetando cart\u00f5es de mem\u00f3ria e solu\u00e7\u00f5es de armazenamento que est\u00e3o continuamente a ir al\u00e9m dos limites de velocidade e desempenho da forma mais segura poss\u00edvel. Com a sua reputa\u00e7\u00e3o de qualidade e fiabilidade, a Angelbird estabelece parcerias com os principais fabricantes de c\u00e2maras e equipamentos de v\u00eddeo como a ARRI, Atomos e RED, desenvolvendo solu\u00e7\u00f5es certificadas \u00e0 medida para alguns dos equipamentos de produ\u00e7\u00e3o mais potentes e caros do mundo. A Angelbird projeta, desenvolve, monta e testa a sua tecnologia internamente, resultando em produtos de alta qualidade que remetem para a precis\u00e3o austr\u00edaca e design minimalista. Como uma das raras empresas que tem em considera\u00e7\u00e3o as necessidades dos profissionais, a Angelbird inova com integridade para fornecer produtos da melhor qualidade e servi\u00e7o ao cliente na ind\u00fastria. Para mais informa\u00e7\u00f5es, consulte <a href=\"http:\/\/www.angelbird.com\">www.angelbird.com<\/a>.<\/p>\n<p><strong>Mais informa\u00e7\u00f5es<\/strong>: <a href=\"https:\/\/www.robisa.es\/pt\/angelbird\/\">https:\/\/www.robisa.es\/pt\/angelbird\/<\/a><\/p>\n<\/div><\/section><\/div><div style='height:50px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div><\/p>\n<div class='avia-button-wrap avia-button-center '><a href='https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/2025_11_02_AVPROSECFEXPRESSV4TIPOB_PT.zip' class='avia-button   avia-icon_select-no avia-color-dark avia-size-large avia-position-center '  target=\"_blank\"   ><span class='avia_iconbox_title' >Descarregue comunicado de imprensa e imagens<\/span><\/a><\/div>\n<div style='height:50px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<div class='av-social-sharing-box  av-social-sharing-box-minimal '><div class='av-share-box'><h5 class='av-share-link-description'>Compartir esta entrada<\/h5><ul class='av-share-box-list noLightbox'><li class='av-share-link av-social-link-facebook' ><a target='_blank' href='http:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/&amp;t=Nova%20linha%20AV%20PRO%20SE%20CFexpress%E2%84%A2%20v4%20type%20B%20da%20Angelbird' aria-hidden='true' data-av_icon='\ue8f3' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share on Facebook'><span class='avia_hidden_link_text'>Share on Facebook<\/span><\/a><\/li><li class='av-share-link av-social-link-twitter' ><a target='_blank' href='https:\/\/twitter.com\/share?text=Nova%20linha%20AV%20PRO%20SE%20CFexpress%E2%84%A2%20v4%20type%20B%20da%20Angelbird&url=https:\/\/www.robisa.es\/pt\/?p=78657' aria-hidden='true' data-av_icon='\ue8f1' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share on Twitter'><span class='avia_hidden_link_text'>Share on Twitter<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin' ><a target='_blank' href='http:\/\/linkedin.com\/shareArticle?mini=true&amp;title=Nova%20linha%20AV%20PRO%20SE%20CFexpress%E2%84%A2%20v4%20type%20B%20da%20Angelbird&amp;url=https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/' aria-hidden='true' data-av_icon='\ue8fc' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share on Linkedin'><span class='avia_hidden_link_text'>Share on Linkedin<\/span><\/a><\/li><li class='av-share-link av-social-link-mail' ><a  href='mailto:?subject=Nova%20linha%20AV%20PRO%20SE%20CFexpress%E2%84%A2%20v4%20type%20B%20da%20Angelbird&amp;body=https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/' aria-hidden='true' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' title='' data-avia-related-tooltip='Share by Mail'><span class='avia_hidden_link_text'>Share by Mail<\/span><\/a><\/li><\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":78912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[165,1749,1742],"tags":[1715,2982,1752,254,1743,2207,2245,1897],"class_list":["post-78657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa-pt","category-nota-de-imprensa-angelbird","category-np-angelbird-pt","tag-angelbird-pt","tag-angelbird-cf-express-pt","tag-cfexpress-pt","tag-fotografia-pt","tag-memoria-pt","tag-mk2-pt","tag-produccion-pt","tag-tarjetamemoria-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA<\/title>\n<meta name=\"description\" content=\"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA\" \/>\n<meta property=\"og:description\" content=\"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/\" \/>\n<meta property=\"og:site_name\" content=\"ROBISA\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/ROBISA\/236622023060912\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T07:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T08:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ROBISA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ROBISA\" \/>\n<meta name=\"twitter:site\" content=\"@ROBISA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ROBISA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/\"},\"author\":{\"name\":\"ROBISA\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#\\\/schema\\\/person\\\/15d196fee14f3e3b10468c6660e90ee7\"},\"headline\":\"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird\",\"datePublished\":\"2025-02-12T07:54:24+00:00\",\"dateModified\":\"2025-02-12T08:13:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/\"},\"wordCount\":2144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AVPROSETIPOB_4.jpg\",\"keywords\":[\"angelbird\",\"Angelbird CF Express\",\"CFexpress\",\"Fotograf\u00eda\",\"memoria\",\"mk2\",\"producci\u00f3n\",\"tarjetamemoria\"],\"articleSection\":[\"COMUNICADO DE IMPRENSA\",\"NOTA DE IMPRENSA ANGELBIRD\",\"NP ANGELBIRD\"],\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/\",\"url\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/\",\"name\":\"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AVPROSETIPOB_4.jpg\",\"datePublished\":\"2025-02-12T07:54:24+00:00\",\"dateModified\":\"2025-02-12T08:13:49+00:00\",\"description\":\"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AVPROSETIPOB_4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AVPROSETIPOB_4.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/\",\"name\":\"ROBISA\",\"description\":\"Los mejores productos de fotograf\u00eda para profesionales y particulares con total garant\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#organization\",\"name\":\"Robisa\",\"url\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/robisa-rgb_negro-NEW-02.png\",\"contentUrl\":\"https:\\\/\\\/www.robisa.es\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/robisa-rgb_negro-NEW-02.png\",\"width\":675,\"height\":298,\"caption\":\"Robisa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/pages\\\/ROBISA\\\/236622023060912\",\"https:\\\/\\\/x.com\\\/ROBISA\",\"https:\\\/\\\/www.instagram.com\\\/robisa.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rodolfo-biber-s-a-robisa-\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/robisavideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.robisa.es\\\/pt\\\/#\\\/schema\\\/person\\\/15d196fee14f3e3b10468c6660e90ee7\",\"name\":\"ROBISA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g\",\"caption\":\"ROBISA\"},\"sameAs\":[\"Susanne\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA","description":"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/","og_locale":"pt_PT","og_type":"article","og_title":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA","og_description":"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird","og_url":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/","og_site_name":"ROBISA","article_publisher":"http:\/\/www.facebook.com\/pages\/ROBISA\/236622023060912","article_published_time":"2025-02-12T07:54:24+00:00","article_modified_time":"2025-02-12T08:13:49+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg","type":"image\/jpeg"}],"author":"ROBISA","twitter_card":"summary_large_image","twitter_creator":"@ROBISA","twitter_site":"@ROBISA","twitter_misc":{"Written by":"ROBISA","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#article","isPartOf":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/"},"author":{"name":"ROBISA","@id":"https:\/\/www.robisa.es\/pt\/#\/schema\/person\/15d196fee14f3e3b10468c6660e90ee7"},"headline":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird","datePublished":"2025-02-12T07:54:24+00:00","dateModified":"2025-02-12T08:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/"},"wordCount":2144,"commentCount":0,"publisher":{"@id":"https:\/\/www.robisa.es\/pt\/#organization"},"image":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#primaryimage"},"thumbnailUrl":"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg","keywords":["angelbird","Angelbird CF Express","CFexpress","Fotograf\u00eda","memoria","mk2","producci\u00f3n","tarjetamemoria"],"articleSection":["COMUNICADO DE IMPRENSA","NOTA DE IMPRENSA ANGELBIRD","NP ANGELBIRD"],"inLanguage":"pt","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/","url":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/","name":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird - ROBISA","isPartOf":{"@id":"https:\/\/www.robisa.es\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#primaryimage"},"image":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#primaryimage"},"thumbnailUrl":"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg","datePublished":"2025-02-12T07:54:24+00:00","dateModified":"2025-02-12T08:13:49+00:00","description":"Nova linha AV PRO SE CFexpress\u2122 v4 type B da Angelbird","breadcrumb":{"@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#primaryimage","url":"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg","contentUrl":"https:\/\/www.robisa.es\/wp-content\/uploads\/2025\/02\/AVPROSETIPOB_4.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.robisa.es\/pt\/nova-linha-av-pro-se-cfexpress-v4-type-b-da-angelbird\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.robisa.es\/pt\/home\/"},{"@type":"ListItem","position":2,"name":"Nova linha AV PRO SE CFexpress&#x2122; v4 type B da Angelbird"}]},{"@type":"WebSite","@id":"https:\/\/www.robisa.es\/pt\/#website","url":"https:\/\/www.robisa.es\/pt\/","name":"ROBISA","description":"Los mejores productos de fotograf\u00eda para profesionales y particulares con total garant\u00eda","publisher":{"@id":"https:\/\/www.robisa.es\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.robisa.es\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/www.robisa.es\/pt\/#organization","name":"Robisa","url":"https:\/\/www.robisa.es\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/www.robisa.es\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.robisa.es\/wp-content\/uploads\/2016\/01\/robisa-rgb_negro-NEW-02.png","contentUrl":"https:\/\/www.robisa.es\/wp-content\/uploads\/2016\/01\/robisa-rgb_negro-NEW-02.png","width":675,"height":298,"caption":"Robisa"},"image":{"@id":"https:\/\/www.robisa.es\/pt\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pages\/ROBISA\/236622023060912","https:\/\/x.com\/ROBISA","https:\/\/www.instagram.com\/robisa.es\/","https:\/\/www.linkedin.com\/company\/rodolfo-biber-s-a-robisa-","http:\/\/www.youtube.com\/user\/robisavideos"]},{"@type":"Person","@id":"https:\/\/www.robisa.es\/pt\/#\/schema\/person\/15d196fee14f3e3b10468c6660e90ee7","name":"ROBISA","image":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/secure.gravatar.com\/avatar\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb4725e6ddc68d14fcbf8ce02bc29fe4030bbf04e92afcd68d39fa1931360a78?s=96&d=mm&r=g","caption":"ROBISA"},"sameAs":["Susanne"]}]}},"_links":{"self":[{"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/posts\/78657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/comments?post=78657"}],"version-history":[{"count":8,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/posts\/78657\/revisions"}],"predecessor-version":[{"id":79004,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/posts\/78657\/revisions\/79004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/media\/78912"}],"wp:attachment":[{"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/media?parent=78657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/categories?post=78657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.robisa.es\/pt\/wp-json\/wp\/v2\/tags?post=78657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}